{"id":356452,"date":"2026-05-13T15:38:50","date_gmt":"2026-05-13T18:38:50","guid":{"rendered":"https:\/\/blogfolhadocomercio.com.br\/wp\/?p=356452"},"modified":"2026-05-13T15:38:50","modified_gmt":"2026-05-13T18:38:50","slug":"prf-apreende-maior-carga-de-cocaina-do-ano-em-goias","status":"publish","type":"post","link":"https:\/\/blogfolhadocomercio.com.br\/wp\/2026\/05\/13\/prf-apreende-maior-carga-de-cocaina-do-ano-em-goias\/","title":{"rendered":"PRF apreende maior carga de coca\u00edna do ano em Goi\u00e1s"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/uploads.maisgoias.com.br\/2026\/05\/13122331\/whatsapp-image-2026-05-13-at-08-51-40-1200x675.webp\" alt=\"Imagem da a\u00e7\u00e3o\" \/><\/p>\n<p>A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu a maior carga de coca\u00edna do ano em Goi\u00e1s. A droga, que saiu de Primavera do Leste, no Mato Grosso, com destino a Uberl\u00e2ndia, em Minas Gerais, foi interceptada em solo goiano, na tarde de ter\u00e7a-feira (12). A apreens\u00e3o de aproximadamente meia tonelada do entorpecente aconteceu na BR-364, no munic\u00edpio de Cachoeira Alta. Os il\u00edcitos estavam em meio a carga de gr\u00e3os.<\/p>\n<p>Durante fiscaliza\u00e7\u00e3o de rotina, os agentes pararam uma carreta que transportava cerca de 39 toneladas de milho em gr\u00e3os. Ao ser questionado sobre a viagem, o motorista, um homem de 44 anos, demonstrou excesso de nervosismo e apresentou respostas contradit\u00f3rias, o que elevou o n\u00edvel de suspeita da equipe.<\/p>\n<p>Diante do comportamento estranho, os policiais decidiram realizar uma busca avan\u00e7ada na carga. Ap\u00f3s removerem parte dos gr\u00e3os de milho, os agentes localizaram 450 tabletes de coca\u00edna, totalizando aproximadamente 500 quilos do entorpecente.<\/p>\n<figure class=\"wp-block-video\"><video src=\"https:\/\/uploads.maisgoias.com.br\/2026\/05\/13122321\/WhatsApp-Video-2026-05-13-at-08.51.36.mp4\" controls=\"controls\" width=\"464\" height=\"832\" data-mce-fragment=\"1\"><\/video><\/figure>\n<p><strong>Leia mais<\/strong><\/p>\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.maisgoias.com.br\/cidades\/go-rotam-apreende-r-5-milhoes-em-drogas-escondidas-em-pneus-de-caminhao\/\" target=\"_blank\" rel=\"noreferrer noopener\">GO: Rotam apreende R$ 5 milh\u00f5es em drogas escondidas em pneus de caminh\u00e3o<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.maisgoias.com.br\/cidades\/grupo-que-produzia-rebites-e-condenado-apos-maior-apreensao-da-prf-em-goias\/#google_vignette\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo que produzia rebites \u00e9 condenado ap\u00f3s maior apreens\u00e3o da PRF em Goi\u00e1s<br \/>\n<\/a><\/strong><\/li>\n<\/ul>\n<p><strong>Disfarce sob o milho<\/strong><\/p>\n<p>Segundo a corpora\u00e7\u00e3o, a estrat\u00e9gia de camuflar a droga sob grandes cargas de gr\u00e3os \u00e9 uma pr\u00e1tica comum para tentar burlar a fiscaliza\u00e7\u00e3o e dificultar o trabalho de c\u00e3es farejadores ou inspe\u00e7\u00f5es superficiais. No entanto, a an\u00e1lise de risco da PRF foi determinante para identificar a irregularidade no ve\u00edculo antes mesmo da abertura do compartimento de carga.<\/p>\n<p>Aos policiais, o condutor afirmou que n\u00e3o sabia da exist\u00eancia da droga e que havia sido contratado apenas para o transporte dos gr\u00e3os.<\/p>\n<h3 id=\"h-investigacao\" class=\"wp-block-heading\"><strong>Investiga\u00e7\u00e3o<\/strong><\/h3>\n<p>O caminhoneiro foi preso em flagrante por tr\u00e1fico de drogas, crime que prev\u00ea penas severas de reclus\u00e3o. Ele foi encaminhado,\u00a0<a href=\"https:\/\/www.gov.br\/prf\/pt-br\/canais-de-atendimento\/unidades-prf\/goias\" target=\"_blank\" rel=\"noreferrer noopener\">junto com o ve\u00edculo e a coca\u00edna<\/a>, para a delegacia da Pol\u00edcia Federal em Jata\u00ed.<\/p>\n<p>Agora, a Pol\u00edcia Federal assume as investiga\u00e7\u00f5es para identificar os respons\u00e1veis pela remessa em Mato Grosso e os receptores da carga em Minas Gerais, buscando desarticular o bra\u00e7o financeiro da organiza\u00e7\u00e3o criminosa envolvida no transporte.<\/p>\n<p><strong>Por Mais Goi\u00e1s<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu a maior carga de coca\u00edna do ano em Goi\u00e1s. A droga, que saiu de Primavera do Leste, no Mato Grosso, com destino a Uberl\u00e2ndia,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":356453,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-356452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas"],"_links":{"self":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/356452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/comments?post=356452"}],"version-history":[{"count":1,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/356452\/revisions"}],"predecessor-version":[{"id":356454,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/356452\/revisions\/356454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/media\/356453"}],"wp:attachment":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/media?parent=356452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/categories?post=356452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/tags?post=356452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}