{"id":352875,"date":"2026-01-26T12:39:35","date_gmt":"2026-01-26T15:39:35","guid":{"rendered":"https:\/\/blogfolhadocomercio.com.br\/wp\/?p=352875"},"modified":"2026-01-26T12:39:35","modified_gmt":"2026-01-26T15:39:35","slug":"pai-e-preso-em-anapolis-por-criar-imagens-pornograficas-da-propria-filha-com-uso-de-inteligencia-artificial","status":"publish","type":"post","link":"https:\/\/blogfolhadocomercio.com.br\/wp\/2026\/01\/26\/pai-e-preso-em-anapolis-por-criar-imagens-pornograficas-da-propria-filha-com-uso-de-inteligencia-artificial\/","title":{"rendered":"Pai \u00e9 preso em An\u00e1polis por criar imagens pornogr\u00e1ficas da pr\u00f3pria filha com uso de intelig\u00eancia artificial"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/uploads.maisgoias.com.br\/2026\/01\/26134120\/pai-x-filha-x-ia-1200x675.webp\" alt=\"pai x filha x ia\" \/><\/p>\n<p>Um homem de 35 anos foi preso por criar imagens pornogr\u00e1ficas da filha adolescente por meio de intelig\u00eancia artificial, em An\u00e1polis. A pris\u00e3o foi realizada na noite de domingo (25), ap\u00f3s a m\u00e3e da jovem procurar a Pol\u00edcia Civil. Al\u00e9m de gerar os conte\u00fados, o suspeito tamb\u00e9m enviava mensagens de cunho sexual e chegou a oferecer dinheiro para a menor ter rela\u00e7\u00f5es sexuais com ele. O homem segue detido.<\/p>\n<div id=\"inread1\" class=\"square-ad\" data-google-query-id=\"CJ3q4e3EqZIDFVM5uQYd2Jwh2w\">\n<div id=\"google_ads_iframe_\/176290677\/maisgoias\/inread1_0__container__\"><\/div>\n<\/div>\n<p>O caso \u00e9 investigado pela\u00a0<a href=\"https:\/\/www.policiacivil.go.gov.br\/\">Delegacia de Prote\u00e7\u00e3o \u00e0 Crian\u00e7a e ao Adolescente (DPCA)<\/a>\u00a0e teve in\u00edcio ap\u00f3s a m\u00e3e da adolescente procurar a delegacia e relatar que o pai, que nunca teve conviv\u00eancia ou proximidade com a filha, passou a enviar mensagens de texto para jovem. No primeiro contato, ele alegava querer se reaproximar e manter um v\u00ednculo familiar. Pouco tempo depois, as conversas passaram a ter conte\u00fado sexual.<\/p>\n<p>De acordo com o relato, o homem enviava mensagens com teor sexual para adolescente, elogios ao corpo dela e ainda ofereceu dinheiro na tentativa de convenc\u00ea-la a manter rela\u00e7\u00f5es sexuais com ele. A situa\u00e7\u00e3o se agravou quando o pai passou a simular fotos pornogr\u00e1ficas da pr\u00f3pria filha utilizando ferramentas de intelig\u00eancia artificial e encaminhando as imagens para ela.<\/p>\n<h3 id=\"h-leia-tambem\" class=\"wp-block-heading\">Leia tamb\u00e9m:<\/h3>\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.maisgoias.com.br\/cidades\/pai-agride-filha-de-12-anos-apos-ser-chamado-para-busca-la-na-casa-de-amiga-em-rio-verde\/\">Pai agride filha de 12 anos ap\u00f3s ser chamado para busc\u00e1-la na casa de amiga em Rio Verde<\/a><\/li>\n<li><a href=\"https:\/\/www.maisgoias.com.br\/cidades\/pais-sao-presos-por-tortura-contra-filha-de-4-anos-em-goiania\/\">Pais s\u00e3o presos por tortura e omiss\u00e3o contra filha de 4 anos em Goi\u00e2nia<br \/>\n<\/a><\/li>\n<\/ul>\n<p>Ap\u00f3s enviar o material, o homem costumava apagar as mensagens assim que percebia que haviam sido visualizadas. Apesar disso, a adolescente conseguiu gravar a tela do celular, registrando todo o conte\u00fado enviado, o que serviu como prova para a investiga\u00e7\u00e3o. A jovem mostrou os registros para a m\u00e3e, que imediatamente procurou a pol\u00edcia.<\/p>\n<div id=\"inread2\" class=\"square-ad\" data-google-query-id=\"CJyxnPXEqZIDFVI4uQYdOFItjg\">\n<div id=\"google_ads_iframe_\/176290677\/maisgoias\/inread2_0__container__\"><\/div>\n<\/div>\n<p>Diante da gravidade dos fatos e da exist\u00eancia de provas, a Pol\u00edcia Civil prendeu o suspeito. Ap\u00f3s a pris\u00e3o, ele foi encaminhado para uma unidade prisional, onde permanece \u00e0 disposi\u00e7\u00e3o do Poder Judici\u00e1rio.<\/p>\n<p>A DPCA refor\u00e7a a import\u00e2ncia de den\u00fancias em casos de viol\u00eancia e explora\u00e7\u00e3o sexual contra crian\u00e7as e adolescentes. Informa\u00e7\u00f5es podem ser repassadas de forma an\u00f4nima pelo Disque-Den\u00fancia da DPCA de An\u00e1polis, pelo WhatsApp (62) 98595-6560 ou Telefone 62-3328-2721.<\/p>\n<p><strong>Por Mais Goi\u00e1s<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 35 anos foi preso por criar imagens pornogr\u00e1ficas da filha adolescente por meio de intelig\u00eancia artificial, em An\u00e1polis. A pris\u00e3o foi realizada na noite de domingo (25),&hellip;<\/p>\n","protected":false},"author":1,"featured_media":352876,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-352875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas"],"_links":{"self":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/352875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/comments?post=352875"}],"version-history":[{"count":1,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/352875\/revisions"}],"predecessor-version":[{"id":352877,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/352875\/revisions\/352877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/media\/352876"}],"wp:attachment":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/media?parent=352875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/categories?post=352875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/tags?post=352875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}