{"id":343397,"date":"2025-07-22T13:00:02","date_gmt":"2025-07-22T16:00:02","guid":{"rendered":"https:\/\/blogfolhadocomercio.com.br\/wp\/?p=343397"},"modified":"2025-07-22T13:00:04","modified_gmt":"2025-07-22T16:00:04","slug":"americano-se-muda-para-russia-para-fugir-de-doutrinacao-lgbt-e-acaba-enviado-para-a-guerra","status":"publish","type":"post","link":"https:\/\/blogfolhadocomercio.com.br\/wp\/2025\/07\/22\/americano-se-muda-para-russia-para-fugir-de-doutrinacao-lgbt-e-acaba-enviado-para-a-guerra\/","title":{"rendered":"Americano se muda para R\u00fassia para fugir de \u2018doutrina\u00e7\u00e3o LGBT+\u2019 e acaba enviado para a guerra"},"content":{"rendered":"\n<p><strong>Fam\u00edlia, que agora enfrenta dificuldades financeiras, pede ora\u00e7\u00f5es nas redes sociais<br><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-content\/uploads\/2025\/07\/image-360-1024x576.png\" alt=\"\" class=\"wp-image-343399\" srcset=\"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-content\/uploads\/2025\/07\/image-360-1024x576.png 1024w, https:\/\/blogfolhadocomercio.com.br\/wp\/wp-content\/uploads\/2025\/07\/image-360-300x169.png 300w, https:\/\/blogfolhadocomercio.com.br\/wp\/wp-content\/uploads\/2025\/07\/image-360-768x432.png 768w, https:\/\/blogfolhadocomercio.com.br\/wp\/wp-content\/uploads\/2025\/07\/image-360-1170x658.png 1170w, https:\/\/blogfolhadocomercio.com.br\/wp\/wp-content\/uploads\/2025\/07\/image-360-585x329.png 585w, https:\/\/blogfolhadocomercio.com.br\/wp\/wp-content\/uploads\/2025\/07\/image-360.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Um americano que se mudou para a&nbsp;<strong>R\u00fassia&nbsp;<\/strong>para fugir do que chamou de<strong>&nbsp;\u2018doutrina\u00e7\u00e3o LGBT+\u2019<\/strong>&nbsp;nos EUA acabou sendo enviado para a linha de frente da&nbsp;<strong>guerra contra a Ucr\u00e2nia.<\/strong>&nbsp;O texano Derek Huffman, de 46 anos, se mudou com a&nbsp;<strong>esposa e as tr\u00eas filhas<\/strong>&nbsp;em busca de um ambiente \u201cmais seguro e alinhado com&nbsp;<strong>valores crist\u00e3os<\/strong>\u201d, mas agora o sonho do conservador virou pesadelo.<\/p>\n\n\n\n<p>A mudan\u00e7a foi viabilizada atrav\u00e9s do programa de vistos \u201cValores Compartilhados\u201d, criado pelo governo russo para atrair estrangeiros contr\u00e1rios ao que o presidente&nbsp;<strong>Vladimir Putin<\/strong>&nbsp;chama de \u201cideologia neoliberal destrutiva\u201d.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>VEJA FOTO:\u00a0<a href=\"https:\/\/www.maisgoias.com.br\/mundo\/ucraniano-capturado-por-forcas-russas-tem-frase-gravada-a-ferro-quente-na-pele-veja-foto\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ucraniano capturado por for\u00e7as russas tem frase gravada a ferro quente na pele<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>Na busca de viver longe das \u201cideologias progressistas\u201d,&nbsp;<strong>Derek Huffman<\/strong>&nbsp;foi alistado nas&nbsp;<a href=\"https:\/\/pt.wikipedia.org\/wiki\/For%C3%A7as_Armadas_da_R%C3%BAssia\" target=\"_blank\" rel=\"noreferrer noopener\">For\u00e7as&nbsp;<\/a>Armadas russas com a promessa de atuar como&nbsp;<strong>soldador&nbsp;<\/strong>e correspondente de guerra, sem ir para a linha de frente. Por\u00e9m, mesmo sem experi\u00eancia militar e sem dominar o idioma russo, ele acabou sendo enviado para uma \u00e1rea do front na&nbsp;<strong>Ucr\u00e2nia<\/strong>.<\/p>\n\n\n\n<p>Sobrou para a fam\u00edlia, que agora enfrenta dificuldades financeiras, pedir&nbsp;<strong>ora\u00e7\u00f5es&nbsp;<\/strong>nas redes sociais. Segundo a esposa,&nbsp;<strong>Derek Huffman<\/strong>&nbsp;precisou pagar do pr\u00f3prio bolso por equipamentos militares e n\u00e3o recebeu o pagamento prometido ap\u00f3s um m\u00eas de servi\u00e7o.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Escritora er\u00f3tica \u00e9 apontada como mentora de\u00a0<a href=\"https:\/\/www.maisgoias.com.br\/mundo\/escritora-erotica-e-apontada-como-mentora-de-operacao-que-destruiu-aeronaves-russas-com-capacidade-nuclear\/\" target=\"_blank\" rel=\"noreferrer noopener\">opera\u00e7\u00e3o que destruiu aeronaves russas com capacidade nuclear<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>A fam\u00edlia Huffman se estabeleceu em uma vila que atrai estrangeiros conservadores insatisfeitos com o estilo de vida ocidental. Segundo relatos, a gota d\u2019\u00e1gua para a mudan\u00e7a ocorreu quando a filha do casal aprendeu sobre diversidade sexual na escola, o que motivou a decis\u00e3o radical.<\/p>\n\n\n\n<p><strong>Derek<\/strong>\u00a0teria se alistado principalmente para acelerar a cidadania russa da fam\u00edlia e obter um b\u00f4nus financeiro. Mas o que era para ser uma fun\u00e7\u00e3o segura virou um risco iminente de vida. A esposa, DeAnna, denuncia nas redes que o marido est\u00e1 sendo usado como soldado comum, mesmo ap\u00f3s garantias de que n\u00e3o teria envolvimento direto nos combates.<\/p>\n\n\n\n<p><strong>Por Mais Goi\u00e1s<br><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fam\u00edlia, que agora enfrenta dificuldades financeiras, pede ora\u00e7\u00f5es nas redes sociais Um americano que se mudou para a&nbsp;R\u00fassia&nbsp;para fugir do que chamou de&nbsp;\u2018doutrina\u00e7\u00e3o LGBT+\u2019&nbsp;nos EUA acabou sendo enviado para a&hellip;<\/p>\n","protected":false},"author":1,"featured_media":343399,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,42],"tags":[],"class_list":["post-343397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-polemica","category-ultimas"],"_links":{"self":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/343397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/comments?post=343397"}],"version-history":[{"count":1,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/343397\/revisions"}],"predecessor-version":[{"id":343400,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/posts\/343397\/revisions\/343400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/media\/343399"}],"wp:attachment":[{"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/media?parent=343397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/categories?post=343397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogfolhadocomercio.com.br\/wp\/wp-json\/wp\/v2\/tags?post=343397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}